{"id":55,"date":"2026-05-26T09:20:45","date_gmt":"2026-05-26T09:20:45","guid":{"rendered":"https:\/\/fr.testaom2025dev.wpenginepowered.com\/?page_id=55"},"modified":"2026-08-31T17:28:39","modified_gmt":"2026-08-31T15:28:39","slug":"carrieres-chez-testa","status":"publish","type":"page","link":"https:\/\/www.testa-omega3.com\/fr\/carrieres-chez-testa\/","title":{"rendered":"Carri\u00e8res chez Testa"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\" style=\"font-size:clamp(0.875rem, 0.875rem + ((1vw - 0.2rem) * 0.469), 1.25rem);line-height:1.6\">Faites de notre mission la v\u00f4tre et venez travailler \u00e0 Amsterdam dans une food scale-up qui a une mission. Aidez-nous \u00e0 construire une marque de compl\u00e9ments alimentaires \u00e0 maturit\u00e9. Testa Omega-3 est vendu dans le monde entier et constitue la marque la plus connue de Wellness Innovations, l&#8217;entreprise sociale qui veut \u00eatre meilleure pour vous et pour l&#8217;oc\u00e9an.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Travailler dans une food scale-up qui a une mission<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Nous voulons secouer le march\u00e9 des om\u00e9ga-3 et faire savoir au monde entier qu&#8217;il faut prendre des om\u00e9ga-3, mais pas issus du poisson.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Notre mission<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Nous sommes Testa Omega-3, une food scale-up internationale avec une mission : d&#8217;ici 2035, remplacer tous les compl\u00e9ments d&#8217;om\u00e9ga-3 \u00e0 base d&#8217;huile de poisson par des produits durables \u00e0 base d&#8217;huile d&#8217;algues. Un quart des captures mondiales de poisson est directement transform\u00e9 en huile de poisson, et ce n&#8217;est pas n\u00e9cessaire : les poissons tirent leurs om\u00e9ga-3 des algues, et nous pouvons faire de m\u00eame. Ainsi, les poissons peuvent continuer \u00e0 nager.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Testa Omega-3 est vendu dans le monde entier et constitue la marque la plus connue de Wellness Innovations, l&#8217;entreprise sociale qui veut \u00eatre meilleure pour vous et pour l&#8217;oc\u00e9an.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Ce que nous offrons<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n\n<li>Beaucoup de latitude pour contribuer et vous d\u00e9velopper dans une entreprise en croissance<\/li>\n\n\n<li>Une ambiance de travail ouverte au sein d&#8217;une \u00e9quipe jeune et ambitieuse<\/li>\n\n\n<li>Un travail qui contribue \u00e0 une soci\u00e9t\u00e9 plus durable<\/li>\n\n\n<li>Des afterworks et des \u00e9v\u00e9nements dans l&#8217;A-Lab, cr\u00e9atif et innovant<\/li>\n\n\n<li>Un bureau \u00e0 Amsterdam, juste \u00e0 c\u00f4t\u00e9 de la gare centrale<\/li>\n\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">\u00cates-vous le talent que nous cherchons ?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">#Socialtalent, #Researchtalent, #Marketingtalent, #Graphismetalent ou #Salestalent ? Vous avez du cran et des id\u00e9es bien \u00e0 vous, vous voulez mettre votre talent au service d&#8217;un monde un peu plus beau et devenir le meilleur dans votre domaine ? Vous souhaitez en apprendre davantage sur le growth hacking, le marketing, la vente ou le design graphique ? Dites-nous ce que vous aimez faire et comment vous pouvez contribuer \u00e0 notre mission.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Int\u00e9ress\u00e9 ?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Envoyez votre CV et votre lettre de motivation \u00e0 <a href=\"mailto:service@testa-omega3.com\">service@testa-omega3.com<\/a>. Nous vous recontacterons dans les meilleurs d\u00e9lais.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Faites de notre mission la v\u00f4tre et venez travailler \u00e0 Amsterdam dans une food scale-up qui a une mission. Aidez-nous \u00e0 construire une marque de compl\u00e9ments alimentaires \u00e0 maturit\u00e9. Testa Omega-3 est vendu dans le monde entier et constitue la marque la plus connue de Wellness Innovations, l&#8217;entreprise sociale qui veut \u00eatre meilleure pour vous [&hellip;]<\/p>\n","protected":false},"author":14,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_gspb_post_css":"","footnotes":""},"class_list":["post-55","page","type-page","status-publish","hentry"],"blocksy_meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Carri\u00e8res chez Testa Omega-3 | Postes<\/title>\n<meta name=\"description\" content=\"Participez \u00e0 une fili\u00e8re om\u00e9ga-3 sans poisson. Rejoignez \u00e0 Amsterdam une food scale-up qui a une mission et envoyez votre candidature spontan\u00e9e.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.testa-omega3.com\/fr\/carrieres-chez-testa\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Carri\u00e8res chez Testa Omega-3 | Postes\" \/>\n<meta property=\"og:description\" content=\"Participez \u00e0 une fili\u00e8re om\u00e9ga-3 sans poisson. Rejoignez \u00e0 Amsterdam une food scale-up qui a une mission et envoyez votre candidature spontan\u00e9e.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.testa-omega3.com\/fr\/carrieres-chez-testa\/\" \/>\n<meta property=\"og:site_name\" content=\"Testa Omega-3 FR\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-31T15:28:39+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.testa-omega3.com\\\/fr\\\/carrieres-chez-testa\\\/\",\"url\":\"https:\\\/\\\/www.testa-omega3.com\\\/fr\\\/carrieres-chez-testa\\\/\",\"name\":\"Carri\u00e8res chez Testa Omega-3 | Postes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.testa-omega3.com\\\/fr\\\/#website\"},\"datePublished\":\"2026-05-26T09:20:45+00:00\",\"dateModified\":\"2026-08-31T15:28:39+00:00\",\"description\":\"Participez \u00e0 une fili\u00e8re om\u00e9ga-3 sans poisson. Rejoignez \u00e0 Amsterdam une food scale-up qui a une mission et envoyez votre candidature spontan\u00e9e.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.testa-omega3.com\\\/fr\\\/carrieres-chez-testa\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.testa-omega3.com\\\/fr\\\/carrieres-chez-testa\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.testa-omega3.com\\\/fr\\\/carrieres-chez-testa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.testa-omega3.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Carri\u00e8res chez Testa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.testa-omega3.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.testa-omega3.com\\\/fr\\\/\",\"name\":\"Testa Omega-3 FR\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.testa-omega3.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.testa-omega3.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.testa-omega3.com\\\/fr\\\/#organization\",\"name\":\"Testa Omega-3 FR\",\"url\":\"https:\\\/\\\/www.testa-omega3.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.testa-omega3.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.testa-omega3.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2026\\\/06\\\/logo.svg\",\"contentUrl\":\"https:\\\/\\\/www.testa-omega3.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2026\\\/06\\\/logo.svg\",\"width\":137,\"height\":51,\"caption\":\"Testa Omega-3 FR\"},\"image\":{\"@id\":\"https:\\\/\\\/www.testa-omega3.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Carri\u00e8res chez Testa Omega-3 | Postes","description":"Participez \u00e0 une fili\u00e8re om\u00e9ga-3 sans poisson. Rejoignez \u00e0 Amsterdam une food scale-up qui a une mission et envoyez votre candidature spontan\u00e9e.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.testa-omega3.com\/fr\/carrieres-chez-testa\/","og_locale":"fr_FR","og_type":"article","og_title":"Carri\u00e8res chez Testa Omega-3 | Postes","og_description":"Participez \u00e0 une fili\u00e8re om\u00e9ga-3 sans poisson. Rejoignez \u00e0 Amsterdam une food scale-up qui a une mission et envoyez votre candidature spontan\u00e9e.","og_url":"https:\/\/www.testa-omega3.com\/fr\/carrieres-chez-testa\/","og_site_name":"Testa Omega-3 FR","article_modified_time":"2026-08-31T15:28:39+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.testa-omega3.com\/fr\/carrieres-chez-testa\/","url":"https:\/\/www.testa-omega3.com\/fr\/carrieres-chez-testa\/","name":"Carri\u00e8res chez Testa Omega-3 | Postes","isPartOf":{"@id":"https:\/\/www.testa-omega3.com\/fr\/#website"},"datePublished":"2026-05-26T09:20:45+00:00","dateModified":"2026-08-31T15:28:39+00:00","description":"Participez \u00e0 une fili\u00e8re om\u00e9ga-3 sans poisson. Rejoignez \u00e0 Amsterdam une food scale-up qui a une mission et envoyez votre candidature spontan\u00e9e.","breadcrumb":{"@id":"https:\/\/www.testa-omega3.com\/fr\/carrieres-chez-testa\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.testa-omega3.com\/fr\/carrieres-chez-testa\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.testa-omega3.com\/fr\/carrieres-chez-testa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.testa-omega3.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Carri\u00e8res chez Testa"}]},{"@type":"WebSite","@id":"https:\/\/www.testa-omega3.com\/fr\/#website","url":"https:\/\/www.testa-omega3.com\/fr\/","name":"Testa Omega-3 FR","description":"","publisher":{"@id":"https:\/\/www.testa-omega3.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.testa-omega3.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.testa-omega3.com\/fr\/#organization","name":"Testa Omega-3 FR","url":"https:\/\/www.testa-omega3.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.testa-omega3.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.testa-omega3.com\/fr\/wp-content\/uploads\/sites\/6\/2026\/06\/logo.svg","contentUrl":"https:\/\/www.testa-omega3.com\/fr\/wp-content\/uploads\/sites\/6\/2026\/06\/logo.svg","width":137,"height":51,"caption":"Testa Omega-3 FR"},"image":{"@id":"https:\/\/www.testa-omega3.com\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.testa-omega3.com\/fr\/wp-json\/wp\/v2\/pages\/55","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.testa-omega3.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.testa-omega3.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.testa-omega3.com\/fr\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/www.testa-omega3.com\/fr\/wp-json\/wp\/v2\/comments?post=55"}],"version-history":[{"count":2,"href":"https:\/\/www.testa-omega3.com\/fr\/wp-json\/wp\/v2\/pages\/55\/revisions"}],"predecessor-version":[{"id":2218,"href":"https:\/\/www.testa-omega3.com\/fr\/wp-json\/wp\/v2\/pages\/55\/revisions\/2218"}],"wp:attachment":[{"href":"https:\/\/www.testa-omega3.com\/fr\/wp-json\/wp\/v2\/media?parent=55"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}